{"id":23712,"date":"2025-09-29T02:42:42","date_gmt":"2025-09-29T02:42:42","guid":{"rendered":"https:\/\/sabuydee.online\/sabuy\/?post_type=product&#038;p=23712"},"modified":"2025-09-29T02:42:43","modified_gmt":"2025-09-29T02:42:43","slug":"boss-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8b%e0%b8%b5%e0%b8%a5%e0%b9%81%e0%b8%81%e0%b9%89","status":"publish","type":"product","link":"https:\/\/sabuydee.online\/sabuy\/shop\/boss-%e0%b8%a3%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b9%83%e0%b8%ab%e0%b8%a1%e0%b9%88-%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8b%e0%b8%b5%e0%b8%a5%e0%b9%81%e0%b8%81%e0%b9%89\/","title":{"rendered":"Boss \u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e32\u0e01\u0e41\u0e01\u0e49\u0e2795 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e1d\u0e32\u0e41\u0e01\u0e49\u0e27 \u0e01\u0e36\u0e48\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e1a\u0e1a\u0e04\u0e31\u0e19\u0e42\u0e22\u0e01"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-23713\" src=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/1-299-300x300.webp\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/1-299-300x300.webp 300w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/1-299-150x150.webp 150w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/1-299.webp 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-23714\" src=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/2-201-300x300.webp\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/2-201-300x300.webp 300w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/2-201-150x150.webp 150w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/2-201.webp 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-23715\" src=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/3-202-300x300.webp\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/3-202-300x300.webp 300w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/3-202-150x150.webp 150w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/3-202.webp 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-23716\" src=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/4-201-300x300.webp\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/4-201-300x300.webp 300w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/4-201-150x150.webp 150w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/4-201-768x768.webp 768w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/4-201-670x670.webp 670w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2025\/09\/4-201.webp 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p class=\"QN2lPu\">\ud83d\udd38 ZB04B DIGITAL<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19\u0e41\u0e01\u0e49\u0e27\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e41\u0e1c\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e1a\u0e1a\u0e1b\u0e38\u0e48\u0e21\u0e01\u0e14<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\ud83d\udd38 ZB04<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e41\u0e1c\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e41\u0e1a\u0e1a\u0e25\u0e39\u0e01\u0e1a\u0e34\u0e14<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\ud83d\udd38 ZB02S<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 (\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e21\u0e38\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21) \u0e21\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e04\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e1b\u0e32\u0e01\u0e41\u0e01\u0e49\u0e27<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e01\u0e49\u0e27\u0e22\u0e35\u0e23\u0e32\u0e1f \u2013 \u0e16\u0e2d\u0e14\u0e10\u0e32\u0e19\u0e44\u0e14\u0e49<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e31\u0e27\u0e04\u0e31\u0e19\u0e42\u0e22\u0e01 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e2d\u0e22\u0e1f\u0e34\u0e25\u0e4c\u0e21<\/p>\n<p class=\"QN2lPu\">\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e21\u0e35\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e43\u0e19\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/p>\n<p class=\"QN2lPu\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e41\u0e01\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e01\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e35\u0e14\u0e33\u0e42\u0e14\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\n<p class=\"QN2lPu\">\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e21\u0e35\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e41\u0e19\u0e1a\u0e44\u0e1b\u0e43\u0e2b\u0e49\u0e43\u0e19\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d<\/p>\n<p class=\"QN2lPu\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e41\u0e01\u0e49\u0e27\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 &#8211; \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e41\u0e01\u0e49\u0e27\u0e1b\u0e32\u0e0195 \u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e32\u0e01 \u0e41\u0e01\u0e49\u0e27 88\/89\/90 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1a\u0e25\u0e2d\u0e0490<\/p>\n<p class=\"QN2lPu\">+\u0e21\u0e49\u0e27\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21 &#8211; \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e41\u0e01\u0e49\u0e27\u0e1b\u0e32\u0e0195 \u0e41\u0e25\u0e30 \u0e21\u0e49\u0e27\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e0b\u0e35\u0e25\u0e41\u0e01\u0e49\u0e271\u0e21\u0e49\u0e27\u0e19<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">#\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e1d\u0e32\u0e41\u0e01\u0e49\u0e27 #\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e41\u0e01\u0e49\u0e27<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"QN2lPu\">\ud83d\udd38 ZB04B DIGITAL<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19\u0e41\u0e01\u0e49\u0e27\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e41\u0e1c\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e41\u0e1a\u0e1a\u0e1b\u0e38\u0e48\u0e21\u0e01\u0e14<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\ud83d\udd38 ZB04<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e41\u0e1c\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e41\u0e1a\u0e1a\u0e25\u0e39\u0e01\u0e1a\u0e34\u0e14<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\ud83d\udd38 ZB02S<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 (\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e21\u0e38\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21) \u0e21\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e04\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e43\u0e2b\u0e49\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e1b\u0e32\u0e01\u0e41\u0e01\u0e49\u0e27<\/p>\n<p class=\"QN2lPu\">\u2022 \u2705 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e01\u0e49\u0e27\u0e22\u0e35\u0e23\u0e32\u0e1f \u2013 \u0e16\u0e2d\u0e14\u0e10\u0e32\u0e19\u0e44\u0e14\u0e49<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e31\u0e27\u0e04\u0e31\u0e19\u0e42\u0e22\u0e01 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e2d\u0e22\u0e1f\u0e34\u0e25\u0e4c\u0e21<\/p>\n<p class=\"QN2lPu\">\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e21\u0e35\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e43\u0e19\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/p>\n<p class=\"QN2lPu\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e41\u0e01\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e01\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e35\u0e14\u0e33\u0e42\u0e14\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19<\/p>\n<p class=\"QN2lPu\">\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19\u0e21\u0e35\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e41\u0e19\u0e1a\u0e44\u0e1b\u0e43\u0e2b\u0e49\u0e43\u0e19\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d<\/p>\n<p class=\"QN2lPu\">\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e41\u0e01\u0e49\u0e27\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 &#8211; \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e41\u0e01\u0e49\u0e27\u0e1b\u0e32\u0e0195 \u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e32\u0e01 \u0e41\u0e01\u0e49\u0e27 88\/89\/90 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1a\u0e25\u0e2d\u0e0490<\/p>\n<p class=\"QN2lPu\">+\u0e21\u0e49\u0e27\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21 &#8211; \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e41\u0e01\u0e49\u0e27\u0e1b\u0e32\u0e0195 \u0e41\u0e25\u0e30 \u0e21\u0e49\u0e27\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e0b\u0e35\u0e25\u0e41\u0e01\u0e49\u0e271\u0e21\u0e49\u0e27\u0e19<\/p>\n<p class=\"QN2lPu\">\n<p class=\"QN2lPu\">#\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e1d\u0e32\u0e41\u0e01\u0e49\u0e27 #\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e35\u0e25\u0e41\u0e01\u0e49\u0e27<\/p>\n","protected":false},"featured_media":23717,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[229],"product_tag":[871],"class_list":["post-23712","product","type-product","status-publish","has-post-thumbnail","product_cat-no-band","product_tag-871","product_brand-affiliate","first","instock","taxable","shipping-taxable","product-type-external"],"_links":{"self":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product\/23712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/comments?post=23712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/media\/23717"}],"wp:attachment":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/media?parent=23712"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product_cat?post=23712"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product_tag?post=23712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}