{"id":14477,"date":"2024-09-30T12:40:43","date_gmt":"2024-09-30T12:40:43","guid":{"rendered":"https:\/\/sabuydee.online\/sabuy\/?post_type=product&#038;p=14477"},"modified":"2024-10-01T12:24:14","modified_gmt":"2024-10-01T12:24:14","slug":"%e0%b8%ab%e0%b8%b1%e0%b8%a7%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b9%81%e0%b8%8a%e0%b8%a1%e0%b8%9e%e0%b8%b9-n70-texapon-n70-%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94-1-%e0%b8%81%e0%b8%b4","status":"publish","type":"product","link":"https:\/\/sabuydee.online\/sabuy\/shop\/%e0%b8%ab%e0%b8%b1%e0%b8%a7%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b9%81%e0%b8%8a%e0%b8%a1%e0%b8%9e%e0%b8%b9-n70-texapon-n70-%e0%b8%82%e0%b8%99%e0%b8%b2%e0%b8%94-1-%e0%b8%81%e0%b8%b4\/","title":{"rendered":"\u0e2b\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e21\u0e1e\u0e39 N70  Texapon N70 \u0e02\u0e19\u0e32\u0e14 1 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21"},"content":{"rendered":"<p>\u0e2b\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e21\u0e1e\u0e39 N70 TexaponN70 \u0e02\u0e19\u0e32\u0e14 1 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-14514 size-large\" src=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2024\/09\/LINE_ALBUM_\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_241001_2-1024x1024.jpg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2024\/09\/LINE_ALBUM_\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_241001_2-1024x1024.jpg 1024w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2024\/09\/LINE_ALBUM_\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_241001_2-300x300.jpg 300w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2024\/09\/LINE_ALBUM_\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_241001_2-150x150.jpg 150w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2024\/09\/LINE_ALBUM_\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_241001_2-768x768.jpg 768w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2024\/09\/LINE_ALBUM_\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_241001_2-670x670.jpg 670w, https:\/\/sabuydee.online\/sabuy\/wp-content\/uploads\/2024\/09\/LINE_ALBUM_\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32_241001_2.jpg 1280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Texapon N70 \u0e2b\u0e23\u0e37\u0e2d N70 \u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d\u0e17\u0e32\u0e07\u0e40\u0e04\u0e21\u0e35\u0e27\u0e48\u0e32 Sodium Lauryl Ether Sulfate \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e32\u0e23\u0e25\u0e14\u0e41\u0e23\u0e07\u0e15\u0e36\u0e07\u0e1c\u0e34\u0e27\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e25\u0e1a \u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e44\u0e14\u0e49\u0e14\u0e35\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1f\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e40\u0e23\u0e47\u0e27 Sodium Lauryl Ether Sulfate(SLES) \u0e21\u0e35\u0e0a\u0e37\u0e48\u0e2d INCI Name \u0e04\u0e37\u0e2d Sodium laureth Sulfate \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e04\u0e19\u0e25\u0e30\u0e15\u0e31\u0e27\u0e01\u0e31\u0e1a Sodium Lauryl Sulfate (SLS)\u0e19\u0e30 \u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e15\u0e23\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35 E \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23 Ethoxylation \u0e42\u0e14\u0e22\u0e19\u0e33\u0e2a\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e15\u0e49\u0e19 \u0e04\u0e37\u0e2d SLS \u0e21\u0e32\u0e17\u0e33\u0e1b\u0e0e\u0e34\u0e01\u0e34\u0e23\u0e34\u0e22\u0e32\u0e01\u0e31\u0e1a ethylene oxide \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e39\u0e07 + catalyst \u0e1c\u0e25\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e04\u0e37\u0e2d \u0e44\u0e14\u0e49 surfactant \u0e17\u0e35\u0e48\u0e23\u0e30\u0e04\u0e32\u0e22\u0e40\u0e04\u0e37\u0e2d\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 SLS \u0e08\u0e36\u0e07\u0e40\u0e2d\u0e32\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 SLS \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e30\u0e25\u0e49\u0e32\u0e07\u0e44\u0e02\u0e21\u0e31\u0e19\u0e2a\u0e39\u0e07 \u0e08\u0e36\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1c\u0e34\u0e27\u0e44\u0e14\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e0a\u0e21\u0e1e\u0e39 \u0e04\u0e23\u0e35\u0e21\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e2a\u0e1a\u0e39\u0e48\u0e40\u0e2b\u0e25\u0e27 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e08\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e25\u0e30\u0e25\u0e32\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e19\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1c\u0e2a\u0e21\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e41\u0e01\u0e07 (Sodium Chloride) Texapon N 70 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 70 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e25\u0e49\u0e32\u0e07\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0a\u0e33\u0e23\u0e30\u0e25\u0e49\u0e32\u0e07\u0e41\u0e17\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e1a\u0e39\u0e48\u0e40\u0e2b\u0e25\u0e27\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e19\u0e49\u0e33\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e21\u0e35\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e40\u0e08\u0e37\u0e2d\u0e08\u0e32\u0e07\u0e01\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 Texapon N 8000 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 28 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e21\u0e35\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e30\u0e04\u0e32\u0e22\u0e40\u0e04\u0e37\u0e2d\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e01\u0e48\u0e2d\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07 \u0e2b\u0e32\u0e01\u0e1c\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e43\u0e19\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e44\u0e19\u0e42\u0e15\u0e23\u0e40\u0e08\u0e19 \u0e08\u0e36\u0e07\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e2d\u0e1a\u0e04\u0e2d\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e15\u0e33\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e15\u0e31\u0e27\u0e43\u0e19\u0e2a\u0e39\u0e15\u0e23<\/p>\n<p>&#8211; \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 : \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e0a\u0e21\u0e1e\u0e39 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e08\u0e32\u0e19 \u0e04\u0e23\u0e35\u0e21\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33<br \/>\n&#8211; \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e21: \u0e25\u0e30\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33<br \/>\n&#8211; \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 : \u0e15\u0e32\u0e21\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e43\u0e19\u0e2a\u0e39\u0e15\u0e23<br \/>\n&#8211; \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32: \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2b\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e34\u0e14\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e43\u0e2b\u0e49\u0e2a\u0e19\u0e34\u0e17 \u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19<br \/>\n&#8211; INCI NAME: Sodium Lauryl Ether Sulfate<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e21\u0e1e\u0e39 N70 TexaponN70 \u0e02\u0e19\u0e32\u0e14 1 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 &nbsp; &#038;nb [&hellip;]<\/p>\n","protected":false},"featured_media":14514,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[139,138,137],"product_tag":[47,204],"class_list":["post-14477","product","type-product","status-publish","has-post-thumbnail","product_cat-139","product_cat-138","product_cat-137","product_tag-daily","product_tag--n70-texapon","product_brand-mtw-chemical","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product\/14477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/comments?post=14477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/media\/14514"}],"wp:attachment":[{"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/media?parent=14477"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product_cat?post=14477"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sabuydee.online\/sabuy\/wp-json\/wp\/v2\/product_tag?post=14477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}